{"id":1805,"date":"2020-12-09T13:21:23","date_gmt":"2020-12-09T13:21:23","guid":{"rendered":"https:\/\/wordpress-486734-1630132.cloudwaysapps.com\/?page_id=1805"},"modified":"2026-06-12T22:06:08","modified_gmt":"2026-06-12T22:06:08","slug":"home","status":"publish","type":"page","link":"https:\/\/innomarkinc.com\/es\/","title":{"rendered":"Home"},"content":{"rendered":"<style>.kb-row-layout-id1805_d9dace-ff > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1805_d9dace-ff > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1805_d9dace-ff > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(40% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1805_d9dace-ff{background-image:url('https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Lab-worker-handling-bottles-generated.png');background-size:cover;background-position:57.99999999999999% 27%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id1805_d9dace-ff > .kt-row-layout-overlay{opacity:1;background:linear-gradient(90deg,var(--global-palette8,#F7FAFC) 41%,rgba(247,250,252,0) 100%);}@media all and (max-width: 1024px){.kb-row-layout-id1805_d9dace-ff > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id1805_d9dace-ff > .kt-row-layout-overlay{opacity:1;background:linear-gradient(90deg,var(--global-palette8,#F7FAFC) 53%,rgba(247,250,252,0) 100%);}}@media all and (max-width: 767px){.kb-row-layout-id1805_d9dace-ff > .kt-row-column-wrap{padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_d9dace-ff alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-left-golden kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1805_4db549-13 > .kt-inside-inner-col,.kadence-column1805_4db549-13 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_4db549-13 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_4db549-13 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_4db549-13 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_4db549-13 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_4db549-13{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_4db549-13{text-align:center;}}@media all and (max-width: 1024px){.kadence-column1805_4db549-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_4db549-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_4db549-13 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c, .wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c[data-kb-block=\"kb-adv-heading1805_39a274-9c\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.3;font-style:normal;letter-spacing:-1px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c[data-kb-block=\"kb-adv-heading1805_39a274-9c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c[data-kb-block=\"kb-adv-heading1805_39a274-9c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c, .wp-block-kadence-advancedheading.kt-adv-heading1805_39a274-9c[data-kb-block=\"kb-adv-heading1805_39a274-9c\"]{font-size:32px;text-align:left!important;}}<\/style>\n<h1 class=\"kt-adv-heading1805_39a274-9c wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_39a274-9c\">Hot Fill Co-Packer for Beverage &amp; Supplement Brands<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5, .wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5[data-kb-block=\"kb-adv-heading1805_451470-c5\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5[data-kb-block=\"kb-adv-heading1805_451470-c5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5[data-kb-block=\"kb-adv-heading1805_451470-c5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5, .wp-block-kadence-advancedheading.kt-adv-heading1805_451470-c5[data-kb-block=\"kb-adv-heading1805_451470-c5\"]{font-size:16px;text-align:left!important;}}<\/style>\n<p class=\"kt-adv-heading1805_451470-c5 wp-block-kadence-advancedheading has-theme-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading1805_451470-c5\">InnoMark is a St. George, Utah hot fill co-packer specializing in contract manufacturing for juices, teas, functional beverages, wellness shots, and nutritional products. USDA Organic certified. With runs as low as 7,500 liters. We are your trusted manufacturing partner for high-quality supplements, juices and bulk superfruits in liquid and powder forms. Explore our extensive range of formulation and manufacturing capabilities, or browse our selection of private-label products.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_aa92c1-22 > .kt-inside-inner-col,.kadence-column1805_aa92c1-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_aa92c1-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_aa92c1-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_aa92c1-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_aa92c1-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_aa92c1-22{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_aa92c1-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_aa92c1-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_aa92c1-22 kvs-md-false kvs-sm-false inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1805_ff03d0-b0{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1805_ff03d0-b0 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1805_ff03d0-b0 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1805_ff03d0-b0 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1805_ff03d0-b0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1805_ff03d0-b0 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1805_ff03d0-b0 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1805_ff03d0-b0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1805_ff03d0-b0 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1805_ff03d0-b0\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1805_ac22c3-0f.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn1805_ac22c3-0f kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"tel:435-627-8464\"><span class=\"kt-btn-inner-text\">(435) 627-8464<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_639fb3-73{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id1805_639fb3-73 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_639fb3-73 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_639fb3-73 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:10px;padding-bottom:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_639fb3-73 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_639fb3-73{margin-top:40px;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_639fb3-73 > .kt-row-column-wrap{padding-top:0px;padding-right:30px;padding-bottom:0px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_639fb3-73{margin-top:60px;margin-bottom:0px;}.kb-row-layout-id1805_639fb3-73 > .kt-row-column-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_639fb3-73 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_689234-5c > .kt-inside-inner-col{padding-right:171px;padding-bottom:0px;padding-left:171px;}.kadence-column1805_689234-5c > .kt-inside-inner-col,.kadence-column1805_689234-5c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_689234-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_689234-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_689234-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_689234-5c > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column1805_689234-5c > .kt-inside-inner-col:before{opacity:0.2;}.kadence-column1805_689234-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_689234-5c > .kt-inside-inner-col{padding-top:0px;padding-right:30px;padding-bottom:0px;padding-left:30px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1805_689234-5c, .kt-inside-inner-col > .kadence-column1805_689234-5c:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1805_689234-5c > .kt-inside-inner-col{padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_689234-5c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_e573c7-d4, .wp-block-kadence-advancedheading.kt-adv-heading1805_e573c7-d4[data-kb-block=\"kb-adv-heading1805_e573c7-d4\"]{margin-top:0px;margin-bottom:30px;text-align:center;font-size:15px;line-height:15px;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e573c7-d4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_e573c7-d4[data-kb-block=\"kb-adv-heading1805_e573c7-d4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e573c7-d4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_e573c7-d4[data-kb-block=\"kb-adv-heading1805_e573c7-d4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1805_e573c7-d4 wp-block-kadence-advancedheading has-theme-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading1805_e573c7-d4\"><strong>how WE work<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55, .wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55[data-kb-block=\"kb-adv-heading1805_3df025-55\"]{margin-top:0px;margin-bottom:30px;text-align:center;line-height:1.2em;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55[data-kb-block=\"kb-adv-heading1805_3df025-55\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55[data-kb-block=\"kb-adv-heading1805_3df025-55\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55, .wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55[data-kb-block=\"kb-adv-heading1805_3df025-55\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55, .wp-block-kadence-advancedheading.kt-adv-heading1805_3df025-55[data-kb-block=\"kb-adv-heading1805_3df025-55\"]{text-align:left!important;}}<\/style>\n<h2 class=\"kt-adv-heading1805_3df025-55 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_3df025-55\">Full turn-key or tolling with R&amp;D formulation services<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_b5c2f8-25, .wp-block-kadence-advancedheading.kt-adv-heading1805_b5c2f8-25[data-kb-block=\"kb-adv-heading1805_b5c2f8-25\"]{margin-top:20px;margin-bottom:20px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_b5c2f8-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_b5c2f8-25[data-kb-block=\"kb-adv-heading1805_b5c2f8-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_b5c2f8-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_b5c2f8-25[data-kb-block=\"kb-adv-heading1805_b5c2f8-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1805_b5c2f8-25 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_b5c2f8-25\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_cc3fa4-98{margin-top:20px;margin-bottom:0px;}.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1805_cc3fa4-98 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_cc3fa4-98{margin-bottom:0px;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap{padding-top:0px;padding-right:10px;padding-bottom:0px;padding-left:10px;grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_cc3fa4-98{margin-top:0px;}.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_cc3fa4-98 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_cc3fa4-98 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-equal kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_f66a30-ee > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column1805_f66a30-ee > .kt-inside-inner-col,.kadence-column1805_f66a30-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_f66a30-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_f66a30-ee > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_f66a30-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_f66a30-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_f66a30-ee{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_f66a30-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_f66a30-ee > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_f66a30-ee inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-info-box1805_37b1e4-4f{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1805_37b1e4-4f{height:auto;align-self:stretch;}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;background:rgba(255,255,255,0.55);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette9, #ffffff);}.kt-info-box1805_37b1e4-4f.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1805_37b1e4-4f .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box1805_37b1e4-4f .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:1024px;height:0px;max-width:100%;}.kt-info-box1805_37b1e4-4f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1805_37b1e4-4f .kt-info-svg-icon-flip, .kt-info-box1805_37b1e4-4f .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:rgba(68,68,68,0.03);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:6px;margin-left:0px;}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:rgba(68,68,68,0.02);}.kt-info-box1805_37b1e4-4f .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:25px;line-height:38px;letter-spacing:-0.2px;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:-4px;margin-right:0px;margin-bottom:25px;margin-left:0px;}.kt-info-box1805_37b1e4-4f .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1805_37b1e4-4f .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}@media all and (max-width: 1024px){.wp-block-kadence-infobox.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-sm, 0.9rem);}}@media all and (max-width: 767px){.kt-info-box1805_37b1e4-4f .kt-blocks-info-box-link-wrap{text-align:left;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1805_37b1e4-4f\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/ship-recraft-icon.png\" alt=\"\" width=\"1024\" height=\"1024\" class=\"kt-info-box-image wp-image-1850\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/ship-recraft-icon.png 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/ship-recraft-icon-300x300.png 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/ship-recraft-icon-150x150.png 150w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/ship-recraft-icon-768x768.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Sourcing ingredients<\/h2><p class=\"kt-blocks-info-box-text\">We have the best connections to source superfruits from around the world. Naturally packed with essential vitamins, minerals, and antioxidants. We source only the best ingredients from trusted suppliers around the world.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_9a6725-7b > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column1805_9a6725-7b > .kt-inside-inner-col{border-right:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column1805_9a6725-7b > .kt-inside-inner-col,.kadence-column1805_9a6725-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_9a6725-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_9a6725-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_9a6725-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_9a6725-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_9a6725-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_9a6725-7b > .kt-inside-inner-col{border-right:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_9a6725-7b > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);border-top:0px solid var(--global-palette3, #1A202C);border-right:0px solid var(--global-palette3, #1A202C);border-bottom:0px solid var(--global-palette3, #1A202C);border-left:0px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_9a6725-7b inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1805_dd5434-8d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1805_dd5434-8d .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255,255,255,0.55);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_dd5434-8d .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette9, #ffffff);}.kt-info-box1805_dd5434-8d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1805_dd5434-8d .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box1805_dd5434-8d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:1024px;height:0px;max-width:100%;}.kt-info-box1805_dd5434-8d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1805_dd5434-8d .kt-info-svg-icon-flip, .kt-info-box1805_dd5434-8d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1805_dd5434-8d .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:rgba(68,68,68,0.03);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_dd5434-8d .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:6px;margin-left:0px;}.kt-info-box1805_dd5434-8d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:rgba(68,68,68,0.02);}.kt-info-box1805_dd5434-8d .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:25px;line-height:38px;letter-spacing:-0.2px;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:-4px;margin-right:0px;margin-bottom:25px;margin-left:0px;}.kt-info-box1805_dd5434-8d .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1805_dd5434-8d .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_dd5434-8d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1805_dd5434-8d .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1805_dd5434-8d .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}@media all and (max-width: 1024px){.wp-block-kadence-infobox.kt-info-box1805_dd5434-8d .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-sm, 0.9rem);}}@media all and (max-width: 767px){.kt-info-box1805_dd5434-8d .kt-blocks-info-box-link-wrap{text-align:left;padding-right:0px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1805_dd5434-8d\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/flask-recraft-icon.png\" alt=\"\" width=\"1024\" height=\"1024\" class=\"kt-info-box-image wp-image-1849\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/flask-recraft-icon.png 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/flask-recraft-icon-300x300.png 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/flask-recraft-icon-150x150.png 150w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/flask-recraft-icon-768x768.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Formulation<\/h2><p class=\"kt-blocks-info-box-text\">Our team of experts and PhD scientists meticulously formulate each product to ensure maximum nutritional efficacy and clean-labels with exquisite organoleptic profiles.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_5d2760-f7 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column1805_5d2760-f7 > .kt-inside-inner-col{border-left:0px solid var(--global-palette7, #EDF2F7);}.kadence-column1805_5d2760-f7 > .kt-inside-inner-col,.kadence-column1805_5d2760-f7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_5d2760-f7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_5d2760-f7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_5d2760-f7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_5d2760-f7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_5d2760-f7{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_5d2760-f7 > .kt-inside-inner-col{border-left:0px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_5d2760-f7 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-xs, 1rem);border-left:0px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}.kadence-column1805_5d2760-f7, .kt-inside-inner-col > .kadence-column1805_5d2760-f7:not(.specificity){margin-bottom:var(--global-kb-spacing-md, 2rem);}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_5d2760-f7 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette9, #ffffff);}.kt-info-box1805_6cef67-3d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1805_6cef67-3d .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box1805_6cef67-3d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:1024px;height:0px;max-width:100%;}.kt-info-box1805_6cef67-3d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1805_6cef67-3d .kt-info-svg-icon-flip, .kt-info-box1805_6cef67-3d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1805_6cef67-3d .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:rgba(68,68,68,0.03);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_6cef67-3d .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:6px;margin-left:0px;}.kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:rgba(68,68,68,0.02);}.kt-info-box1805_6cef67-3d .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:25px;line-height:38px;letter-spacing:-0.2px;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:-4px;margin-right:0px;margin-bottom:25px;margin-left:0px;}.kt-info-box1805_6cef67-3d .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1805_6cef67-3d .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap{text-align:center;}}@media all and (max-width: 1024px){.kt-info-box1805_6cef67-3d .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}@media all and (max-width: 1024px){.wp-block-kadence-infobox.kt-info-box1805_6cef67-3d .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-sm, 0.9rem);}}@media all and (max-width: 767px){.kt-info-box1805_6cef67-3d .kt-blocks-info-box-link-wrap{text-align:left;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1805_6cef67-3d\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center kb-info-tablet-halign-center kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/cogs-recraft-icon.png\" alt=\"\" width=\"1024\" height=\"1024\" class=\"kt-info-box-image wp-image-1848\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/cogs-recraft-icon.png 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/cogs-recraft-icon-300x300.png 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/cogs-recraft-icon-150x150.png 150w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/cogs-recraft-icon-768x768.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Production<\/h2><p class=\"kt-blocks-info-box-text\">Using state of the art equipment and technology we will ensure quality, speed, and regulatory compliance for any of your hot fill bottling, encapsulating, stick packs, pouches and labeling needs.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_a29324-2c{margin-top:40px;margin-bottom:0px;}.kb-row-layout-id1805_a29324-2c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_a29324-2c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_a29324-2c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_a29324-2c > .kt-row-layout-overlay{opacity:1;background:linear-gradient(360deg, var(--global-palette8) 84%, rgba(0, 181, 226, 0) 0%);}@media all and (max-width: 1024px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_a29324-2c{margin-top:0px;margin-bottom:0px;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_a29324-2c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1805_a29324-2c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_a29324-2c alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_3b6416-16 > .kt-inside-inner-col{display:flex;}.kadence-column1805_3b6416-16 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column1805_3b6416-16 > .kt-inside-inner-col,.kadence-column1805_3b6416-16 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_3b6416-16 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_3b6416-16 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column1805_3b6416-16 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1805_3b6416-16{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1805_3b6416-16{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1805_3b6416-16 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column1805_3b6416-16 > .kt-inside-inner-col:before{opacity:1;background-image:url('https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/blurry-gradient-haikei-gold-white.svg');background-size:cover;background-position:93% 93%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column1805_3b6416-16{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_3b6416-16 > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1805_3b6416-16{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1805_3b6416-16{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1805_3b6416-16 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1805_3b6416-16{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1805_3b6416-16{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1805_3b6416-16 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column1805_3b6416-16 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_3b6416-16 kb-section-has-overlay inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_a40316-37{margin-top:90px;margin-bottom:0px;}.kb-row-layout-id1805_a40316-37 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_a40316-37 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_a40316-37 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1805_a40316-37 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_a40316-37{margin-top:var(--global-kb-spacing-md, 2rem);}}@media all and (max-width: 1024px){.kb-row-layout-id1805_a40316-37 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1805_a40316-37 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id1805_a40316-37 .img-pos3 { width: 205px; position: absolute; right: 358px; bottom: 15px;}.kb-row-layout-id1805_a40316-37 .img-pos4 { width: 162px; position: absolute; right: 190px; bottom: 33px; z-index: -10;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_a40316-37 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_21ef35-06 > .kt-inside-inner-col{padding-top:60px;padding-right:60px;padding-bottom:60px;padding-left:20px;}.kadence-column1805_21ef35-06 > .kt-inside-inner-col,.kadence-column1805_21ef35-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_21ef35-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_21ef35-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_21ef35-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_21ef35-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_21ef35-06{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_21ef35-06 > .kt-inside-inner-col{padding-top:0px;padding-right:30px;padding-bottom:30px;padding-left:30px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1805_21ef35-06, .kt-inside-inner-col > .kadence-column1805_21ef35-06:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1805_21ef35-06 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_21ef35-06 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01, .wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01[data-kb-block=\"kb-adv-heading1805_e4d344-01\"]{margin-top:20px;margin-bottom:20px;line-height:1.2em;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01[data-kb-block=\"kb-adv-heading1805_e4d344-01\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01[data-kb-block=\"kb-adv-heading1805_e4d344-01\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01, .wp-block-kadence-advancedheading.kt-adv-heading1805_e4d344-01[data-kb-block=\"kb-adv-heading1805_e4d344-01\"]{font-size:20px;}}<\/style>\n<h2 class=\"kt-adv-heading1805_e4d344-01 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_e4d344-01\">InnoMark has developed and manufactured thousands of client products in our 25 years of experience.<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e, .wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e[data-kb-block=\"kb-adv-heading1805_e9bfb2-8e\"]{margin-top:20px;margin-bottom:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e[data-kb-block=\"kb-adv-heading1805_e9bfb2-8e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e[data-kb-block=\"kb-adv-heading1805_e9bfb2-8e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e, .wp-block-kadence-advancedheading.kt-adv-heading1805_e9bfb2-8e[data-kb-block=\"kb-adv-heading1805_e9bfb2-8e\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);}}<\/style>\n<p class=\"kt-adv-heading1805_e9bfb2-8e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_e9bfb2-8e\">InnoMark Inc. fills a rare B2B partnership niche in the middle of your growth stage. Low MOQ&#8217;s for incubating brands with resources and equipment to scale up smoothly. Our hot fill co-packer expertise can guide you from a great idea to an established brand without the growing pains of starting over with new manufacturing facilities along the way.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_7e619c-af > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column1805_7e619c-af > .kt-inside-inner-col,.kadence-column1805_7e619c-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_7e619c-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_7e619c-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_7e619c-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_7e619c-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_7e619c-af{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_7e619c-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_7e619c-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_7e619c-af inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1805_ece239-4d{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1805_ece239-4d .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1805_ece239-4d .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1805_ece239-4d .kb-slide-item .kb-gal-image-radius img{border-radius:4px 4px 4px 4px;;}<\/style><div class=\"kb-gallery-wrap-id-1805_ece239-4d alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1805_ece239-4d kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/labeling-machine-stock.jpg\" width=\"360\" height=\"240\" alt=\"\" data-full-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/labeling-machine-stock.jpg\" data-light-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/labeling-machine-stock.jpg\" data-id=\"1828\" class=\"wp-image-1828\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/labeling-machine-stock.jpg 360w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/labeling-machine-stock-300x200.jpg 300w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image.jpeg\" width=\"2524\" height=\"1893\" alt=\"\" data-full-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image.jpeg\" data-light-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image.jpeg\" data-id=\"1813\" class=\"wp-image-1813\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image.jpeg 2524w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image-300x225.jpeg 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image-1024x768.jpeg 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image-768x576.jpeg 768w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image-1536x1152.jpeg 1536w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/red-juice-smaple-image-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2524px) 100vw, 2524px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/bottles-stock-image-1.jpg\" width=\"360\" height=\"240\" alt=\"\" data-full-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/bottles-stock-image-1.jpg\" data-light-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/bottles-stock-image-1.jpg\" data-id=\"1826\" class=\"wp-image-1826\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/bottles-stock-image-1.jpg 360w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/bottles-stock-image-1-300x200.jpg 300w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/colored-juice-stock-image.jpg\" width=\"559\" height=\"240\" alt=\"\" data-full-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/colored-juice-stock-image.jpg\" data-light-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/colored-juice-stock-image.jpg\" data-id=\"1827\" class=\"wp-image-1827\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/colored-juice-stock-image.jpg 559w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/colored-juice-stock-image-300x129.jpg 300w\" sizes=\"(max-width: 559px) 100vw, 559px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image.jpeg\" width=\"2025\" height=\"1519\" alt=\"\" data-full-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image.jpeg\" data-light-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image.jpeg\" data-id=\"1811\" class=\"wp-image-1811\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image.jpeg 2025w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image-300x225.jpeg 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image-1024x768.jpeg 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image-768x576.jpeg 768w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/powder-sample-image-1536x1152.jpeg 1536w\" sizes=\"(max-width: 2025px) 100vw, 2025px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image.jpeg\" width=\"2560\" height=\"1920\" alt=\"\" data-full-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image.jpeg\" data-light-image=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image.jpeg\" data-id=\"1815\" class=\"wp-image-1815\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image.jpeg 2560w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image-300x225.jpeg 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image-1024x768.jpeg 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image-768x576.jpeg 768w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image-1536x1152.jpeg 1536w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/05\/yellow-liquid-sample-image-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_2655a3-5c{margin-top:90px;margin-bottom:90px;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;grid-template-columns:minmax(0, calc(62% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(38% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id1805_2655a3-5c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_2655a3-5c{margin-top:60px;margin-bottom:0px;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap{padding-top:0px;padding-right:10px;padding-bottom:12px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_2655a3-5c{margin-top:30px;margin-bottom:0px;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id1805_2655a3-5c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_2655a3-5c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_839973-3a > .kt-inside-inner-col,.kadence-column1805_839973-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_839973-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_839973-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_839973-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_839973-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_839973-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_839973-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_839973-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_839973-3a\"><div class=\"kt-inside-inner-col\">\n<div style=\"aspect-ratio:16\/9;min-height:unset;\" class=\"wp-block-cover is-light has-aspect-ratio\"><video class=\"wp-block-cover__video-background intrinsic-ignore\" autoplay muted loop playsinline src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Video-for-webpage.mov\" data-object-fit=\"cover\"><\/video><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col{padding-top:60px;padding-right:60px;padding-bottom:60px;padding-left:60px;}.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col,.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_0f2b9b-64{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col{padding-top:0px;padding-right:60px;padding-bottom:0px;padding-left:60px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1805_0f2b9b-64, .kt-inside-inner-col > .kadence-column1805_0f2b9b-64:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1805_0f2b9b-64 > .kt-inside-inner-col{padding-top:0px;padding-right:30px;padding-bottom:0px;padding-left:30px;flex-direction:column;justify-content:center;}.kadence-column1805_0f2b9b-64, .kt-inside-inner-col > .kadence-column1805_0f2b9b-64:not(.specificity){margin-top:30px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_0f2b9b-64 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_9ee6a6-78, .wp-block-kadence-advancedheading.kt-adv-heading1805_9ee6a6-78[data-kb-block=\"kb-adv-heading1805_9ee6a6-78\"]{margin-top:20px;margin-bottom:20px;line-height:1.2em;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_9ee6a6-78 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_9ee6a6-78[data-kb-block=\"kb-adv-heading1805_9ee6a6-78\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_9ee6a6-78 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_9ee6a6-78[data-kb-block=\"kb-adv-heading1805_9ee6a6-78\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1805_9ee6a6-78 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_9ee6a6-78\">Fast start-up without the usual frustrations<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_bbc11c-0e, .wp-block-kadence-advancedheading.kt-adv-heading1805_bbc11c-0e[data-kb-block=\"kb-adv-heading1805_bbc11c-0e\"]{margin-top:20px;margin-bottom:20px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_bbc11c-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_bbc11c-0e[data-kb-block=\"kb-adv-heading1805_bbc11c-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_bbc11c-0e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_bbc11c-0e[data-kb-block=\"kb-adv-heading1805_bbc11c-0e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1805_bbc11c-0e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_bbc11c-0e\">From compliant custom printed labels and packaging to complete R&amp;D services, the Innomark team has done it all. Get your product to market first with our efficient manufacturing of shelf-stable consumable products, done your way.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1805_b7fa2a-df > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_b7fa2a-df > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_b7fa2a-df > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_b7fa2a-df > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1805_b7fa2a-df > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1805_b7fa2a-df > .kt-row-column-wrap{padding-right:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_b7fa2a-df alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col,.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_c7cbc3-08{text-align:center;}.kadence-column1805_c7cbc3-08{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_c7cbc3-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_c7cbc3-08\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a, .wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a[data-kb-block=\"kb-adv-heading1805_c38e31-8a\"]{margin-right:var(--global-kb-spacing-4xl, 8rem);margin-left:var(--global-kb-spacing-4xl, 8rem);text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a[data-kb-block=\"kb-adv-heading1805_c38e31-8a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a[data-kb-block=\"kb-adv-heading1805_c38e31-8a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a, .wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a[data-kb-block=\"kb-adv-heading1805_c38e31-8a\"]{margin-right:var(--global-kb-spacing-md, 2rem);margin-left:var(--global-kb-spacing-md, 2rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a, .wp-block-kadence-advancedheading.kt-adv-heading1805_c38e31-8a[data-kb-block=\"kb-adv-heading1805_c38e31-8a\"]{margin-right:0px;margin-left:0px;line-height:0.9;}}<\/style>\n<h2 class=\"kt-adv-heading1805_c38e31-8a wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_c38e31-8a\">Customer Assurance<\/h2>\n\n\n\n<p class=\"has-text-align-left has-small-font-size wp-block-paragraph\" style=\"line-height:1.4\">Certifications and verifications confirm that your products have been evaluated and approved by reputable third-party organizations, ensuring they meet or exceed industry standards. This commitment to quality helps build trust and maintain transparency with valued customers. Our team can navigate the various product labelling requirements that allow marketing to stand out to an increasingly quality focused and educated consumer.<\/p>\n\n\n\n<p class=\"has-text-align-left has-small-font-size wp-block-paragraph\" style=\"line-height:1.4\">Choose InnoMark Inc. for certified, high-quality nutritional products, supplements, and superfruits. Experience the difference that rigorous standards and lab-verified quality can make in your health and wellness journey.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_e8248e-28 > .kt-inside-inner-col,.kadence-column1805_e8248e-28 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_e8248e-28 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_e8248e-28 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_e8248e-28 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_e8248e-28 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_e8248e-28{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_e8248e-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_e8248e-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_e8248e-28\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id1805_a290d2-b4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_a290d2-b4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_a290d2-b4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(6, minmax(0, 1fr));}.kb-row-layout-id1805_a290d2-b4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1805_a290d2-b4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:repeat(6, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1805_a290d2-b4 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(3, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_a290d2-b4 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-6-columns kt-row-layout-equal kt-tab-layout-equal kt-mobile-layout-three-grid kt-row-valign-top\">\n<style>.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col,.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_2b1ee2-35{text-align:center;}.kadence-column1805_2b1ee2-35{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_2b1ee2-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_2b1ee2-35\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1805_8d1414-21:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image1805_8d1414-21.kb-image-is-ratio-size, .kb-image1805_8d1414-21 .kb-image-is-ratio-size{max-width:122px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_8d1414-21.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_8d1414-21 .kb-image-is-ratio-size{align-self:unset;}.kb-image1805_8d1414-21 figure{max-width:122px;}.kb-image1805_8d1414-21 .image-is-svg, .kb-image1805_8d1414-21 .image-is-svg img{width:100%;}.kb-image1805_8d1414-21 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image1805_8d1414-21:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:var(--global-kb-spacing-xxs, 0.5rem);margin-left:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image1805_8d1414-21\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"3001\" height=\"3005\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free.png\" alt=\"\" class=\"kb-img wp-image-1944\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free.png 3001w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free-300x300.png 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free-1024x1024.png 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free-150x150.png 150w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free-768x769.png 768w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free-1534x1536.png 1534w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Certified-Gluten-Free-2045x2048.png 2045w\" sizes=\"(max-width: 3001px) 100vw, 3001px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_b08e39-6b, .wp-block-kadence-advancedheading.kt-adv-heading1805_b08e39-6b[data-kb-block=\"kb-adv-heading1805_b08e39-6b\"]{margin-top:0px;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_b08e39-6b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_b08e39-6b[data-kb-block=\"kb-adv-heading1805_b08e39-6b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_b08e39-6b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_b08e39-6b[data-kb-block=\"kb-adv-heading1805_b08e39-6b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1805_b08e39-6b wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_b08e39-6b\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_081ed9-1e > .kt-inside-inner-col,.kadence-column1805_081ed9-1e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_081ed9-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_081ed9-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_081ed9-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_081ed9-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_081ed9-1e{text-align:center;}.kadence-column1805_081ed9-1e{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_081ed9-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_081ed9-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_081ed9-1e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1805_179260-0d:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image1805_179260-0d.kb-image-is-ratio-size, .kb-image1805_179260-0d .kb-image-is-ratio-size{max-width:124px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_179260-0d.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_179260-0d .kb-image-is-ratio-size{align-self:unset;}.kb-image1805_179260-0d figure{max-width:124px;}.kb-image1805_179260-0d .image-is-svg, .kb-image1805_179260-0d .image-is-svg img{width:100%;}.kb-image1805_179260-0d .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image1805_179260-0d:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:var(--global-kb-spacing-xxs, 0.5rem);margin-left:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image1805_179260-0d\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"195\" height=\"195\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/haccp_certified.jpg\" alt=\"\" class=\"kb-img wp-image-1936\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/haccp_certified.jpg 195w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/haccp_certified-150x150.jpg 150w\" sizes=\"(max-width: 195px) 100vw, 195px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_0ce8d7-27, .wp-block-kadence-advancedheading.kt-adv-heading1805_0ce8d7-27[data-kb-block=\"kb-adv-heading1805_0ce8d7-27\"]{margin-top:0px;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_0ce8d7-27 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_0ce8d7-27[data-kb-block=\"kb-adv-heading1805_0ce8d7-27\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_0ce8d7-27 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_0ce8d7-27[data-kb-block=\"kb-adv-heading1805_0ce8d7-27\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1805_0ce8d7-27 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_0ce8d7-27\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_d36ad7-42 > .kt-inside-inner-col,.kadence-column1805_d36ad7-42 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_d36ad7-42 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_d36ad7-42 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_d36ad7-42 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_d36ad7-42 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_d36ad7-42{text-align:center;}.kadence-column1805_d36ad7-42{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_d36ad7-42 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_d36ad7-42 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_d36ad7-42\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1805_5813e9-7e:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image1805_5813e9-7e.kb-image-is-ratio-size, .kb-image1805_5813e9-7e .kb-image-is-ratio-size{max-width:116px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_5813e9-7e.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_5813e9-7e .kb-image-is-ratio-size{align-self:unset;}.kb-image1805_5813e9-7e figure{max-width:116px;}.kb-image1805_5813e9-7e .image-is-svg, .kb-image1805_5813e9-7e .image-is-svg img{width:100%;}.kb-image1805_5813e9-7e:not(.kb-image-is-ratio-size) .kb-img, .kb-image1805_5813e9-7e.kb-image-is-ratio-size{padding-right:0px;padding-left:0px;}.kb-image1805_5813e9-7e .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image1805_5813e9-7e:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:var(--global-kb-spacing-xxs, 0.5rem);margin-left:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image1805_5813e9-7e\"><figure class=\"aligncenter size-thumbnail\"><img decoding=\"async\" width=\"195\" height=\"195\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/fair_trade_certified_logo-cmyk.png\" alt=\"\" class=\"kb-img wp-image-1941\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/fair_trade_certified_logo-cmyk.png 195w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/fair_trade_certified_logo-cmyk-150x150.png 150w\" sizes=\"(max-width: 195px) 100vw, 195px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_1343dd-05, .wp-block-kadence-advancedheading.kt-adv-heading1805_1343dd-05[data-kb-block=\"kb-adv-heading1805_1343dd-05\"]{margin-top:0px;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_1343dd-05 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_1343dd-05[data-kb-block=\"kb-adv-heading1805_1343dd-05\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_1343dd-05 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_1343dd-05[data-kb-block=\"kb-adv-heading1805_1343dd-05\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1805_1343dd-05 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_1343dd-05\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col,.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_2cf6f8-f8{text-align:center;}.kadence-column1805_2cf6f8-f8{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_2cf6f8-f8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_2cf6f8-f8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1805_050299-75:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image1805_050299-75.kb-image-is-ratio-size, .kb-image1805_050299-75 .kb-image-is-ratio-size{max-width:116px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_050299-75.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_050299-75 .kb-image-is-ratio-size{align-self:unset;}.kb-image1805_050299-75 figure{max-width:116px;}.kb-image1805_050299-75 .image-is-svg, .kb-image1805_050299-75 .image-is-svg img{width:100%;}.kb-image1805_050299-75 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image1805_050299-75:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:var(--global-kb-spacing-xxs, 0.5rem);margin-left:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image1805_050299-75\"><figure class=\"aligncenter size-thumbnail\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/USDA-Black-and-White-Organic-Seal-GIF-150x150.gif\" alt=\"\" class=\"kb-img wp-image-1933\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/USDA-Black-and-White-Organic-Seal-GIF-150x150.gif 150w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/USDA-Black-and-White-Organic-Seal-GIF-300x300.gif 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_338dba-2f, .wp-block-kadence-advancedheading.kt-adv-heading1805_338dba-2f[data-kb-block=\"kb-adv-heading1805_338dba-2f\"]{margin-top:0px;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_338dba-2f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_338dba-2f[data-kb-block=\"kb-adv-heading1805_338dba-2f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_338dba-2f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_338dba-2f[data-kb-block=\"kb-adv-heading1805_338dba-2f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1805_338dba-2f wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_338dba-2f\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_8579d6-1c > .kt-inside-inner-col,.kadence-column1805_8579d6-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_8579d6-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_8579d6-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_8579d6-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_8579d6-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_8579d6-1c{text-align:center;}.kadence-column1805_8579d6-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_8579d6-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_8579d6-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_8579d6-1c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1805_ca36d6-91:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image1805_ca36d6-91.kb-image-is-ratio-size, .kb-image1805_ca36d6-91 .kb-image-is-ratio-size{max-width:103px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_ca36d6-91.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_ca36d6-91 .kb-image-is-ratio-size{align-self:unset;}.kb-image1805_ca36d6-91 figure{max-width:103px;}.kb-image1805_ca36d6-91 .image-is-svg, .kb-image1805_ca36d6-91 .image-is-svg img{width:100%;}.kb-image1805_ca36d6-91 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image1805_ca36d6-91:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);margin-left:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image1805_ca36d6-91\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" width=\"214\" height=\"300\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/NonGmoProject-meat-label-214x300.jpg\" alt=\"\" class=\"kb-img wp-image-1945\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/NonGmoProject-meat-label-214x300.jpg 214w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/NonGmoProject-meat-label.jpg 692w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_1cc0a5-e2, .wp-block-kadence-advancedheading.kt-adv-heading1805_1cc0a5-e2[data-kb-block=\"kb-adv-heading1805_1cc0a5-e2\"]{margin-top:0px;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_1cc0a5-e2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_1cc0a5-e2[data-kb-block=\"kb-adv-heading1805_1cc0a5-e2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_1cc0a5-e2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_1cc0a5-e2[data-kb-block=\"kb-adv-heading1805_1cc0a5-e2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1805_1cc0a5-e2 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_1cc0a5-e2\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_1a7d61-13 > .kt-inside-inner-col,.kadence-column1805_1a7d61-13 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_1a7d61-13 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_1a7d61-13 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_1a7d61-13 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_1a7d61-13 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_1a7d61-13{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_1a7d61-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_1a7d61-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_1a7d61-13\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1805_eb1757-35 > .kt-inside-inner-col,.kadence-column1805_eb1757-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_eb1757-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_eb1757-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_eb1757-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_eb1757-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_eb1757-35{text-align:center;}.kadence-column1805_eb1757-35{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_eb1757-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_eb1757-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_eb1757-35\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1805_bff3f9-ce:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image1805_bff3f9-ce.kb-image-is-ratio-size, .kb-image1805_bff3f9-ce .kb-image-is-ratio-size{max-width:92px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_bff3f9-ce.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1805_bff3f9-ce .kb-image-is-ratio-size{align-self:unset;}.kb-image1805_bff3f9-ce figure{max-width:92px;}.kb-image1805_bff3f9-ce .image-is-svg, .kb-image1805_bff3f9-ce .image-is-svg img{width:100%;}.kb-image1805_bff3f9-ce .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image1805_bff3f9-ce:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-xs, 1rem);}}@media all and (max-width: 1024px){.kb-image1805_bff3f9-ce:not(.kb-image-is-ratio-size) .kb-img, .kb-image1805_bff3f9-ce.kb-image-is-ratio-size{padding-right:0px;padding-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image1805_bff3f9-ce\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"191\" height=\"215\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Kosher-TabletK.jpg\" alt=\"\" class=\"kb-img wp-image-1940\"\/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_997e62-51, .wp-block-kadence-advancedheading.kt-adv-heading1805_997e62-51[data-kb-block=\"kb-adv-heading1805_997e62-51\"]{margin-top:0px;font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_997e62-51 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_997e62-51[data-kb-block=\"kb-adv-heading1805_997e62-51\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_997e62-51 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_997e62-51[data-kb-block=\"kb-adv-heading1805_997e62-51\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1805_997e62-51 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1805_997e62-51\">Kosher Certified<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_ae3131-54{margin-top:20px;margin-bottom:0px;}.kb-row-layout-id1805_ae3131-54 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_ae3131-54 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_ae3131-54 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:60px;padding-right:10px;padding-bottom:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_ae3131-54 > .kt-row-layout-overlay{opacity:0.30;background-image:url('https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/background-overlay-dots-surrounding-circle-768x280.png');background-size:160% auto;background-position:100% 63%;background-attachment:fixed;background-repeat:repeat;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id1805_ae3131-54 > .kt-row-layout-overlay{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_ae3131-54{margin-top:60px;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_ae3131-54 > .kt-row-column-wrap{padding-right:30px;padding-bottom:10px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_ae3131-54{margin-top:60px;}.kb-row-layout-id1805_ae3131-54 > .kt-row-column-wrap{padding-right:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_ae3131-54 > .kt-row-layout-overlay{opacity:0.18;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_ae3131-54 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal kt-jarallax\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_db713d-6e > .kt-inside-inner-col{padding-right:171px;padding-bottom:0px;padding-left:171px;}.kadence-column1805_db713d-6e > .kt-inside-inner-col,.kadence-column1805_db713d-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_db713d-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_db713d-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_db713d-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_db713d-6e > .kt-inside-inner-col:before{opacity:0.76;}.kadence-column1805_db713d-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_db713d-6e > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1805_db713d-6e, .kt-inside-inner-col > .kadence-column1805_db713d-6e:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1805_db713d-6e > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}.kadence-column1805_db713d-6e, .kt-inside-inner-col > .kadence-column1805_db713d-6e:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_db713d-6e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44, .wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44[data-kb-block=\"kb-adv-heading1805_3c4568-44\"]{margin-top:0px;margin-bottom:30px;text-align:center;font-size:50px;line-height:50px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44[data-kb-block=\"kb-adv-heading1805_3c4568-44\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44[data-kb-block=\"kb-adv-heading1805_3c4568-44\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44, .wp-block-kadence-advancedheading.kt-adv-heading1805_3c4568-44[data-kb-block=\"kb-adv-heading1805_3c4568-44\"]{margin-right:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-xs, 1rem);font-size:38px;}}<\/style>\n<h2 id=\"meet-team\" class=\"kt-adv-heading1805_3c4568-44 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_3c4568-44\">Meet the Team<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc, .wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc[data-kb-block=\"kb-adv-heading1805_e74fa0-dc\"]{margin-top:20px;margin-bottom:20px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc[data-kb-block=\"kb-adv-heading1805_e74fa0-dc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc[data-kb-block=\"kb-adv-heading1805_e74fa0-dc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc, .wp-block-kadence-advancedheading.kt-adv-heading1805_e74fa0-dc[data-kb-block=\"kb-adv-heading1805_e74fa0-dc\"]{margin-right:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-xs, 1rem);font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading1805_e74fa0-dc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_e74fa0-dc\">The experienced and dedicated professional executives who are eager to help your brand navigate every step of the process from an idea to retail shelf.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_497095-f9{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:100px;padding-left:0px;}.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1805_497095-f9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1805_497095-f9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_497095-f9 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1805_35e347-32 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column1805_35e347-32 > .kt-inside-inner-col,.kadence-column1805_35e347-32 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_35e347-32 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_35e347-32 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_35e347-32 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_35e347-32 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_35e347-32{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_35e347-32 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_35e347-32 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_35e347-32 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0.01);}.kt-info-box1805_2a637a-03.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1805_2a637a-03 .kadence-info-box-image-inner-intrisic-container{max-width:800px;}.kt-info-box1805_2a637a-03 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:97.7322%;width:1852px;height:0px;max-width:100%;}.kt-info-box1805_2a637a-03 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1805_2a637a-03 .kt-info-svg-icon-flip, .kt-info-box1805_2a637a-03 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-radius:3px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box1805_2a637a-03 .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette5, #4A5568);font-size:18px;line-height:27px;font-style:normal;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:-5px;margin-left:0px;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap:hover h6.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box1805_2a637a-03 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.wp-block-kadence-infobox.kt-info-box1805_2a637a-03 .kt-blocks-info-box-text{font-size:16px;line-height:29px;font-style:normal;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1805_2a637a-03 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1805_2a637a-03\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\" href=\"https:\/\/www.linkedin.com\/in\/nathan-hench-mba\/\" target=\"_blank\" rel=\"noopener\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/03\/nate-profile-edit.jpg\" alt=\"\" width=\"1852\" height=\"1810\" class=\"kt-info-box-image wp-image-2567\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h6 class=\"kt-blocks-info-box-title\">Nathan Hench<\/h6><p class=\"kt-blocks-info-box-text\">President<\/p><\/div><\/a><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1805_ef83bf-4a .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1805_ef83bf-4a .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-spacer.kt-block-spacer-1805_ef83bf-4a .kt-block-spacer{height:20px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1805_ef83bf-4a\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:14px\"><summary>Click to read more about Nate<\/summary><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_4238a2-25, .wp-block-kadence-advancedheading.kt-adv-heading1805_4238a2-25[data-kb-block=\"kb-adv-heading1805_4238a2-25\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_4238a2-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_4238a2-25[data-kb-block=\"kb-adv-heading1805_4238a2-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_4238a2-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_4238a2-25[data-kb-block=\"kb-adv-heading1805_4238a2-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1805_4238a2-25 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_4238a2-25\">Nate Hench was born and raised in Baltimore, Maryland. A love for sports and a strong East-coast mentality were two influences that he brought with him to the West where he has resided for most of his adult-life. In fact, you\u2019ll see hints of both aspects creep out from time to time while conducting business or yelling at the New York Yankees or Baltimore Ravens on a TV screen. Nate now calls St. George home due to its sunny weather year-around, beautiful red-rock canyons, and countless outdoor adventures. He studied International Business at Brigham Young University prior to completing his Bachelor of Business Administration at Dixie University and a Master of Business Administration through Western Governors University. Nate shares two vibrant daughters with his beautiful wife, Elizabeth. The Hench family is grounded in a firm belief that the success to life is the continual pursuance of a proper balance between God, Family, and Diligent Work.<\/p>\n<\/details>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col,.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_4c9c3c-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_4c9c3c-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_4c9c3c-7f inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0.01);}.kt-info-box1805_10f50d-25.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1805_10f50d-25 .kadence-info-box-image-inner-intrisic-container{max-width:800px;}.kt-info-box1805_10f50d-25 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:108.8235%;width:1020px;height:0px;max-width:100%;}.kt-info-box1805_10f50d-25 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1805_10f50d-25 .kt-info-svg-icon-flip, .kt-info-box1805_10f50d-25 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-radius:3px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box1805_10f50d-25 .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette5, #4A5568);font-size:18px;line-height:27px;font-style:normal;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:-5px;margin-left:0px;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap:hover h6.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box1805_10f50d-25 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.wp-block-kadence-infobox.kt-info-box1805_10f50d-25 .kt-blocks-info-box-text{font-size:16px;line-height:29px;font-style:normal;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1805_10f50d-25 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1805_10f50d-25\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/05\/A01DB167-F6CE-4499-B388-85AFFE101E25-e1779811715793.jpg\" alt=\"\" width=\"1020\" height=\"1110\" class=\"kt-info-box-image wp-image-2626\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/05\/A01DB167-F6CE-4499-B388-85AFFE101E25-e1779811715793.jpg 1020w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/05\/A01DB167-F6CE-4499-B388-85AFFE101E25-e1779811715793-276x300.jpg 276w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/05\/A01DB167-F6CE-4499-B388-85AFFE101E25-e1779811715793-941x1024.jpg 941w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/05\/A01DB167-F6CE-4499-B388-85AFFE101E25-e1779811715793-768x836.jpg 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h6 class=\"kt-blocks-info-box-title\">Holly Loveless<\/h6><p class=\"kt-blocks-info-box-text\">Sales Lead<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1805_f49b34-74 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1805_f49b34-74 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-spacer.kt-block-spacer-1805_f49b34-74 .kt-block-spacer{height:20px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1805_f49b34-74\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:14px\"><summary>Click to read more about Holly<\/summary><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_9fc945-a9, .wp-block-kadence-advancedheading.kt-adv-heading1805_9fc945-a9[data-kb-block=\"kb-adv-heading1805_9fc945-a9\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_9fc945-a9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_9fc945-a9[data-kb-block=\"kb-adv-heading1805_9fc945-a9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_9fc945-a9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_9fc945-a9[data-kb-block=\"kb-adv-heading1805_9fc945-a9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1805_9fc945-a9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_9fc945-a9\">Born in Southern Utah and raised in Las Vegas, Holly moved back to Southern Utah 21 years ago and now proudly calls it home. She brings over 20 years of customer service experience into her role as Sales Manager. Her passion for building strong client relationships, combined with her industry knowledge and approachable personality, helps create a seamless experience for customers from start to finish. Holly is dedicated to helping brands bring their products to life through high-quality manufacturing solutions, including powder sticks, capsules, and hot fill bottles. Outside of work, she enjoys staying active, spending time in the gym, living a healthy lifestyle, and spending quality time with her kids and granddaughter.<\/p>\n<\/details>\n<\/div><\/div>\n\n\n<style>.kadence-column1805_956c99-8e > .kt-inside-inner-col,.kadence-column1805_956c99-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_956c99-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_956c99-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_956c99-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_956c99-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_956c99-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_956c99-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_956c99-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_956c99-8e\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1805_f55cff-70 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column1805_f55cff-70 > .kt-inside-inner-col,.kadence-column1805_f55cff-70 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_f55cff-70 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_f55cff-70 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_f55cff-70 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_f55cff-70 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_f55cff-70{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_f55cff-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_f55cff-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_f55cff-70 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0.01);}.kt-info-box1805_2e6b6a-34.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1805_2e6b6a-34 .kadence-info-box-image-inner-intrisic-container{max-width:800px;}.kt-info-box1805_2e6b6a-34 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:99.5025%;width:1407px;height:0px;max-width:100%;}.kt-info-box1805_2e6b6a-34 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1805_2e6b6a-34 .kt-info-svg-icon-flip, .kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-radius:3px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box1805_2e6b6a-34 .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette5, #4A5568);font-size:18px;line-height:27px;font-style:normal;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:-5px;margin-left:0px;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap:hover h6.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box1805_2e6b6a-34 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.wp-block-kadence-infobox.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-text{font-size:16px;line-height:29px;font-style:normal;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1805_2e6b6a-34 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1805_2e6b6a-34\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/in\/edgar-pineda-9b371145\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/03\/edgar-scaled-e1774279453785.jpg\" alt=\"\" width=\"1407\" height=\"1400\" class=\"kt-info-box-image wp-image-2571\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/03\/edgar-scaled-e1774279453785.jpg 1407w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/03\/edgar-scaled-e1774279453785-300x300.jpg 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/03\/edgar-scaled-e1774279453785-1024x1019.jpg 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/03\/edgar-scaled-e1774279453785-150x150.jpg 150w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2026\/03\/edgar-scaled-e1774279453785-768x764.jpg 768w\" sizes=\"(max-width: 1407px) 100vw, 1407px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h6 class=\"kt-blocks-info-box-title\"><br>Edgar Pineda<\/h6><p class=\"kt-blocks-info-box-text\">Operations Manager<\/p><\/div><\/a><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1805_30ff1c-33 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1805_30ff1c-33 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-spacer.kt-block-spacer-1805_30ff1c-33 .kt-block-spacer{height:20px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1805_30ff1c-33\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" style=\"font-size:14px\"><summary>Click to read more about Edgar<\/summary><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_a0757e-13, .wp-block-kadence-advancedheading.kt-adv-heading1805_a0757e-13[data-kb-block=\"kb-adv-heading1805_a0757e-13\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_a0757e-13 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_a0757e-13[data-kb-block=\"kb-adv-heading1805_a0757e-13\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_a0757e-13 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_a0757e-13[data-kb-block=\"kb-adv-heading1805_a0757e-13\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1805_a0757e-13 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_a0757e-13\">Edgar Pineda Edgar was born in Lima, Peru, and has always been driven to explore new horizons. He holds a degree in Chemical Engineering from Peru and later continued his studies at BYU in Utah. His professional career began at BASF in the Glasurit division, where he worked in sales for major chemical companies.<br>After moving to San Jose, California, Edgar transitioned into the food manufacturing industry, holding roles in project engineering, operations, and safety and compliance (FDA\/SQF). During this time, he also earned his MBA in San Jose. Edgar has extensive experience in food manufacturing equipment and processes, including quality, safety, production, and engineering. He has worked with major organizations such as Unilever, Dean Foods, Albertsons, and Walmart.<br>While Edgar\u2019s wife is a BYU graduate and has roots in Utah, their children were born in California. As a family, they enjoy seeking out new experiences and spending time with friends and loved ones.<\/p>\n<\/details>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column1805_40f409-f9 > .kt-inside-inner-col,.kadence-column1805_40f409-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_40f409-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_40f409-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_40f409-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_40f409-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_40f409-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_40f409-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_40f409-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_40f409-f9\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1805_07e0bd-9a > .kt-inside-inner-col,.kadence-column1805_07e0bd-9a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_07e0bd-9a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_07e0bd-9a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_07e0bd-9a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_07e0bd-9a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_07e0bd-9a{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_07e0bd-9a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_07e0bd-9a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_07e0bd-9a\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-id1805_aab331-2c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_aab331-2c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_aab331-2c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1805_aab331-2c > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id1805_aab331-2c .kt-row-layout-bottom-sep{height:80px;}.kb-row-layout-id1805_aab331-2c .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id1805_aab331-2c .kt-row-layout-bottom-sep svg{fill:var(--global-palette9, #ffffff)!important;}@media all and (max-width: 1024px){.kb-row-layout-id1805_aab331-2c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id1805_aab331-2c .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id1805_aab331-2c .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id1805_aab331-2c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_aab331-2c .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id1805_aab331-2c .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_aab331-2c alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-sltr\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M0,0l1000,100l-1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);border-top:2px solid rgba(24,24,25,0.5);border-right:2px solid rgba(24,24,25,0.5);border-bottom:2px solid rgba(24,24,25,0.5);border-left:2px solid rgba(24,24,25,0.5);}.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col,.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_ffbfe5-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col{border-top:2px solid rgba(24,24,25,0.5);border-right:2px solid rgba(24,24,25,0.5);border-bottom:2px solid rgba(24,24,25,0.5);border-left:2px solid rgba(24,24,25,0.5);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_ffbfe5-4a > .kt-inside-inner-col{border-top:2px solid rgba(24,24,25,0.5);border-right:2px solid rgba(24,24,25,0.5);border-bottom:2px solid rgba(24,24,25,0.5);border-left:2px solid rgba(24,24,25,0.5);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_ffbfe5-4a\"><div class=\"kt-inside-inner-col\"><style>.kb-google-maps-container1805_b33c96-6f{height:450px;}<\/style><div class=\"kb-google-maps-container kb-google-maps-container1805_b33c96-6f wp-block-kadence-googlemaps\" data-mapid=\"1805_b33c966f\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=6&#038;maptype=roadmap&#038;q=innomark+inc.\"\n\t\t\t\t\t\t\ttitle=\"Google map of innomark inc.\"><\/iframe><\/div><script>function kb_google_map1805_b33c966f() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map1805_b33c966f\"), {\n\t\t\t\t\t    zoom: 6,\n\t\t\t\t\t    center: center,});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script><\/div><\/div>\n\n\n<style>.kadence-column1805_448232-93 > .kt-inside-inner-col{display:flex;}.kadence-column1805_448232-93 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column1805_448232-93 > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);border-top:2px solid rgba(24,24,25,0.5);border-right:2px solid rgba(24,24,25,0.5);border-bottom:2px solid rgba(24,24,25,0.5);border-left:2px solid rgba(24,24,25,0.5);}.kadence-column1805_448232-93 > .kt-inside-inner-col,.kadence-column1805_448232-93 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_448232-93 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_448232-93 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column1805_448232-93 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1805_448232-93 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1805_448232-93 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_448232-93 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column1805_448232-93 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_448232-93{text-align:left;}.kadence-column1805_448232-93{position:relative;}.kadence-column1805_448232-93, .kt-inside-inner-col > .kadence-column1805_448232-93:not(.specificity){margin-top:0px;}@media all and (max-width: 1024px){.kadence-column1805_448232-93 > .kt-inside-inner-col{border-top:2px solid rgba(24,24,25,0.5);border-right:2px solid rgba(24,24,25,0.5);border-bottom:2px solid rgba(24,24,25,0.5);border-left:2px solid rgba(24,24,25,0.5);flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column1805_448232-93 > .kt-inside-inner-col{border-top:2px solid rgba(24,24,25,0.5);border-right:2px solid rgba(24,24,25,0.5);border-bottom:2px solid rgba(24,24,25,0.5);border-left:2px solid rgba(24,24,25,0.5);flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_448232-93\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_ab1f4d-45, .wp-block-kadence-advancedheading.kt-adv-heading1805_ab1f4d-45[data-kb-block=\"kb-adv-heading1805_ab1f4d-45\"]{padding-top:0px;padding-bottom:0px;margin-top:0px;margin-bottom:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_ab1f4d-45 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_ab1f4d-45[data-kb-block=\"kb-adv-heading1805_ab1f4d-45\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_ab1f4d-45 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_ab1f4d-45[data-kb-block=\"kb-adv-heading1805_ab1f4d-45\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1805_ab1f4d-45 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_ab1f4d-45\">Saint George, UT<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"2457\" height=\"849\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Innomark-building-1-scaled-e1717568742859.jpg\" alt=\"\" class=\"wp-image-1961\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Innomark-building-1-scaled-e1717568742859.jpg 2457w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Innomark-building-1-scaled-e1717568742859-300x104.jpg 300w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Innomark-building-1-scaled-e1717568742859-1024x354.jpg 1024w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Innomark-building-1-scaled-e1717568742859-768x265.jpg 768w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Innomark-building-1-scaled-e1717568742859-1536x531.jpg 1536w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/Innomark-building-1-scaled-e1717568742859-2048x708.jpg 2048w\" sizes=\"(max-width: 2457px) 100vw, 2457px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-theme-palette-9-background-color has-background has-small-font-size wp-block-paragraph\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">Nestled in the southwestern corner of Utah, Saint George along I-15 is an ideal location for manufacturing companies. Its strategic position provides convenient access to major markets across the Western United States, including Las Vegas, Los Angeles, Phoenix, Denver, Boise and Salt Lake City. This central location ensures efficient distribution and reduced shipping costs, making it a prime spot for businesses aiming to optimize their logistics.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column1805_89738f-69 > .kt-inside-inner-col{padding-top:0px;padding-right:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-3xl, 6.5rem);}.kadence-column1805_89738f-69 > .kt-inside-inner-col,.kadence-column1805_89738f-69 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_89738f-69 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_89738f-69 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_89738f-69 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_89738f-69 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column1805_89738f-69 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_89738f-69{position:relative;}.kadence-column1805_89738f-69, .kt-inside-inner-col > .kadence-column1805_89738f-69:not(.specificity){margin-top:0px;}@media all and (max-width: 1024px){.kadence-column1805_89738f-69 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_89738f-69 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_89738f-69\" id=\"faqs\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_d56c2b-81, .wp-block-kadence-advancedheading.kt-adv-heading1805_d56c2b-81[data-kb-block=\"kb-adv-heading1805_d56c2b-81\"]{padding-top:0px;padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xs, 1rem);margin-top:0px;text-align:left;font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading1805_d56c2b-81 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_d56c2b-81[data-kb-block=\"kb-adv-heading1805_d56c2b-81\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_d56c2b-81 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_d56c2b-81[data-kb-block=\"kb-adv-heading1805_d56c2b-81\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1805_d56c2b-81 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1805_d56c2b-81\">FAQs<\/h2>\n\n\n<style>.kt-accordion-id1805_54347f-46 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id1805_54347f-46 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:var(--global-palette8, #F7FAFC);border-top-style:solid;border-right-color:var(--global-palette8, #F7FAFC);border-right-style:solid;border-bottom-color:var(--global-palette8, #F7FAFC);border-bottom-style:solid;border-left-color:var(--global-palette8, #F7FAFC);border-left-style:solid;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id1805_54347f-46 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1805_54347f-46:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id1805_54347f-46 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);}}@media all and (max-width: 1024px){.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);}}@media all and (max-width: 1024px){.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette8, #F7FAFC);border-top-style:solid;border-right-color:var(--global-palette8, #F7FAFC);border-right-style:solid;border-bottom-color:var(--global-palette8, #F7FAFC);border-bottom-style:solid;border-left-color:var(--global-palette8, #F7FAFC);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1805_54347f-46 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1805_54347f-46 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1805_54347f-46 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id1805_54347f-46 .kt-accordion-panel-inner{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);font-size:14px;}.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1805_54347f-46 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette8, #F7FAFC);border-top-style:solid;border-right-color:var(--global-palette8, #F7FAFC);border-right-style:solid;border-bottom-color:var(--global-palette8, #F7FAFC);border-bottom-style:solid;border-left-color:var(--global-palette8, #F7FAFC);border-left-style:solid;}.kt-accordion-id1805_54347f-46 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1805_54347f-46 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1805_54347f-46 kt-accordion-has-11-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"true\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-11 kt-pane1805_093a06-68\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is hot fill manufacturing?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_748200-01, .wp-block-kadence-advancedheading.kt-adv-heading1805_748200-01[data-kb-block=\"kb-adv-heading1805_748200-01\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_748200-01 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_748200-01[data-kb-block=\"kb-adv-heading1805_748200-01\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_748200-01 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_748200-01[data-kb-block=\"kb-adv-heading1805_748200-01\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1805_748200-01 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_748200-01\">Hot fill manufacturing is a beverage and liquid production process where the product is heated to 185\u2013200\u00b0F, filled into containers at that temperature, sealed, and then inverted to sanitize the cap before cooling. The high fill temperature pasteurizes both the product and the package in a single step, creating a shelf-stable product without the need for chemical preservatives or aseptic filling equipment.<br>Hot fill is the preferred process for juices, teas, functional beverages, wellness shots, broths, sauces, and many nutritional liquids. Any product that needs ambient shelf stability while maintaining clean-label ingredients. It&#8217;s especially well-suited for USDA Organic and natural products, since the heat itself does the preservation work that synthetic preservatives would otherwise handle.<br>Compared to cold fill, hot fill products last significantly longer on the shelf without refrigeration. Compared to aseptic filling, hot fill requires far less capital equipment, which is why hot fill co-packers like InnoMark can offer smaller minimum order quantities. This makes the process accessible to emerging brands that aren&#8217;t yet ready for the volumes large aseptic lines demand.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1805_7cb916-fc\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Can InnoMark hot fill our liquid product?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4, .wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4[data-kb-block=\"kb-adv-heading1805_b883b3-b4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4[data-kb-block=\"kb-adv-heading1805_b883b3-b4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4[data-kb-block=\"kb-adv-heading1805_b883b3-b4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4, .wp-block-kadence-advancedheading.kt-adv-heading1805_b883b3-b4[data-kb-block=\"kb-adv-heading1805_b883b3-b4\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_b883b3-b4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_b883b3-b4\">We have equipment capabilities to hot fill (flash pasteurization) plastic and glass containers from 8oz to 1 gallon with consumable liquids for humans. There are many other variables for a hot fill co-packer such as specific certifications and product specifications which may also affect our potential business relationship and should be discussed directly. We are able handle hot fill aluminum cans. We do NOT produce carbonated, or high pH refrigerated products, or alcohol products.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane1805_8d8bc1-7d\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Can InnoMark fill our powder products?&nbsp;<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7, .wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7[data-kb-block=\"kb-adv-heading1805_14813e-f7\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7[data-kb-block=\"kb-adv-heading1805_14813e-f7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7[data-kb-block=\"kb-adv-heading1805_14813e-f7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7, .wp-block-kadence-advancedheading.kt-adv-heading1805_14813e-f7[data-kb-block=\"kb-adv-heading1805_14813e-f7\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_14813e-f7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_14813e-f7\">Yes! Our current equipment blends and fills tubs, bags, stick packs, and capsules with nutritional powders for human consumption.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane1805_4c1bcc-b1\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Do we need a complete formula, or can InnoMark help with R&amp;D?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61, .wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61[data-kb-block=\"kb-adv-heading1805_190f1c-61\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61[data-kb-block=\"kb-adv-heading1805_190f1c-61\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61[data-kb-block=\"kb-adv-heading1805_190f1c-61\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61, .wp-block-kadence-advancedheading.kt-adv-heading1805_190f1c-61[data-kb-block=\"kb-adv-heading1805_190f1c-61\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_190f1c-61 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_190f1c-61\">InnoMark employs a very experienced full R&amp;D lab with nutritionists, a PhD research formulator, and lab technicians to help clients adjust or create new products. This service can be provided and priced separately. It is included for our partners that are producing with us. We can also provide accelerated shelf life studies when necessary.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane1805_77c6c5-82\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What are InnoMark\u2019s lead times?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76, .wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76[data-kb-block=\"kb-adv-heading1805_a8b871-76\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76[data-kb-block=\"kb-adv-heading1805_a8b871-76\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76[data-kb-block=\"kb-adv-heading1805_a8b871-76\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76, .wp-block-kadence-advancedheading.kt-adv-heading1805_a8b871-76[data-kb-block=\"kb-adv-heading1805_a8b871-76\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_a8b871-76 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_a8b871-76\">InnoMark generally requires 4-6 weeks to produce turnkey products from the time a purchase order is submitted.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane1805_8f1d01-61\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">How long is the expiration date of our packaged products that InnoMark manufactures?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49, .wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49[data-kb-block=\"kb-adv-heading1805_5749ae-49\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49[data-kb-block=\"kb-adv-heading1805_5749ae-49\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49[data-kb-block=\"kb-adv-heading1805_5749ae-49\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49, .wp-block-kadence-advancedheading.kt-adv-heading1805_5749ae-49[data-kb-block=\"kb-adv-heading1805_5749ae-49\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_5749ae-49 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_5749ae-49\">The shelf life can be upwards of 2 years for properly packaged food items through our hot fill shelf-stable processes. The FDA requires a shelf-life study to be done at the client\u2019s expense for labeling. Our default is a manufacturing (MFG) date until the testing is completed. We can provide accelerated shelf life studies.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane1805_5d55a2-b3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Can InnoMark provide the materials and components for contract manufacturing?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4, .wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4[data-kb-block=\"kb-adv-heading1805_edbf7f-b4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4[data-kb-block=\"kb-adv-heading1805_edbf7f-b4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4[data-kb-block=\"kb-adv-heading1805_edbf7f-b4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4, .wp-block-kadence-advancedheading.kt-adv-heading1805_edbf7f-b4[data-kb-block=\"kb-adv-heading1805_edbf7f-b4\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_edbf7f-b4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_edbf7f-b4\">Yes, we offer full tolling or full turnkey packaging, or any combination of the two, assuming suppliers can provide appropriate certifications for safety and the components fit our equipment.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane1805_dabc04-d6\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Does InnoMark handle fulfillment services also?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65, .wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65[data-kb-block=\"kb-adv-heading1805_d3a8b4-65\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65[data-kb-block=\"kb-adv-heading1805_d3a8b4-65\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65[data-kb-block=\"kb-adv-heading1805_d3a8b4-65\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65, .wp-block-kadence-advancedheading.kt-adv-heading1805_d3a8b4-65[data-kb-block=\"kb-adv-heading1805_d3a8b4-65\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_d3a8b4-65 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_d3a8b4-65\">Yes, at an additional cost, or we will ship the completed, labeled, and case-packed pallets of product to your 3PL or distribution warehouse.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-9 kt-pane1805_51fbd3-64\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What are the MOQs for InnoMark?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33, .wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33[data-kb-block=\"kb-adv-heading1805_28f48b-33\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33[data-kb-block=\"kb-adv-heading1805_28f48b-33\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33[data-kb-block=\"kb-adv-heading1805_28f48b-33\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33, .wp-block-kadence-advancedheading.kt-adv-heading1805_28f48b-33[data-kb-block=\"kb-adv-heading1805_28f48b-33\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_28f48b-33 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_28f48b-33\">We are very flexible and can do small and large runs. MOQs affect pricing dramatically but are negotiable. Hot fill Liquid production runs must be larger than 7,000 liters for equipment to function properly. Powders must be larger than 3,000 kgs. <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-10 kt-pane1805_9bdfb1-4f\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Does InnoMark extend payment terms?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a, .wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a[data-kb-block=\"kb-adv-heading1805_590c8e-3a\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a[data-kb-block=\"kb-adv-heading1805_590c8e-3a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a[data-kb-block=\"kb-adv-heading1805_590c8e-3a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a, .wp-block-kadence-advancedheading.kt-adv-heading1805_590c8e-3a[data-kb-block=\"kb-adv-heading1805_590c8e-3a\"]{font-size:12px;}}<\/style>\n<p class=\"kt-adv-heading1805_590c8e-3a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1805_590c8e-3a\">We help our partners balance supply chain and cash flow. To become a partner a history of on payments must be established. New orders require 50% deposit with the purchase order and the remaining 50% payment at the time of delivery. 100% upfront can be required for the first order.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1805_07b522-f0{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:40px;padding-right:20px;padding-bottom:20px;padding-left:20px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1805_07b522-f0 > .kt-row-layout-overlay{opacity:1;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id1805_07b522-f0 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1805_07b522-f0 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1805_ad3a37-fc > .kt-inside-inner-col,.kadence-column1805_ad3a37-fc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_ad3a37-fc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_ad3a37-fc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_ad3a37-fc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_ad3a37-fc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_ad3a37-fc{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_ad3a37-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_ad3a37-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_ad3a37-fc\"><div class=\"kt-inside-inner-col\"><style>.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-1805_a03b76-45 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_1805_a03b76-45_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_1805_a03b76-45_0\" data-label=\"Name\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_1805_a03b76-45_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_1805_a03b76-45_1\" data-label=\"Email\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_1805_a03b76-45_2\">Message<span class=\"required\">*<\/span><\/label><textarea name=\"kb_field_2\" id=\"kb_field_1805_a03b76-45_2\" data-label=\"Message\" type=\"textarea\" placeholder=\"\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-2\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"1805_a03b76-45\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"1805\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-1805_a03b76-45 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n\n<style>.kadence-column1805_4ff321-cc > .kt-inside-inner-col,.kadence-column1805_4ff321-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1805_4ff321-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1805_4ff321-cc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1805_4ff321-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1805_4ff321-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1805_4ff321-cc{position:relative;}@media all and (max-width: 1024px){.kadence-column1805_4ff321-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1805_4ff321-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1805_4ff321-cc\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-cover\"><img decoding=\"async\" width=\"443\" height=\"261\" class=\"wp-block-cover__image-background wp-image-2157\" alt=\"\" src=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/smoke-background.png\" data-object-fit=\"cover\" srcset=\"https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/smoke-background.png 443w, https:\/\/innomarkinc.com\/wp-content\/uploads\/2024\/06\/smoke-background-300x177.png 300w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-theme-palette-1-background-color has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\">Contact us today to begin the process of launching your nutraceuticals or superfruit product line!<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Hot Fill Co-Packer for Beverage &amp; Supplement Brands InnoMark is a St. George, Utah hot fill co-packer specializing in contract manufacturing for juices, teas, functional beverages, wellness shots, and nutritional products. USDA Organic certified. With runs as low as 7,500 liters. We are your trusted manufacturing partner for high-quality supplements, juices and bulk superfruits in&#8230;<\/p>","protected":false},"author":4,"featured_media":1965,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-1805","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/pages\/1805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/comments?post=1805"}],"version-history":[{"count":215,"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/pages\/1805\/revisions"}],"predecessor-version":[{"id":2633,"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/pages\/1805\/revisions\/2633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/media\/1965"}],"wp:attachment":[{"href":"https:\/\/innomarkinc.com\/es\/wp-json\/wp\/v2\/media?parent=1805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}